{"id":24568,"date":"2026-05-13T03:02:48","date_gmt":"2026-05-13T01:02:48","guid":{"rendered":"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/"},"modified":"2026-05-13T03:02:48","modified_gmt":"2026-05-13T01:02:48","slug":"quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo","status":"publish","type":"post","link":"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/","title":{"rendered":"Quando il valore nominale non basta: quantificare l\u2019incertezza con la simulazione Monte Carlo"},"content":{"rendered":"<div>\n<div style=\"margin: 5px 5% 10px 5%;\"><img loading=\"lazy\" src=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-1-fotor-2026040811545.jpg?resize=750%2C521&#038;ssl=1\" width=\"750\" height=\"521\" title=\"\" alt=\"\" data-recalc-dims=\"1\"><\/div>\n<div>\n<p><strong>Nel mondo reale, le valvole non leggono i disegni.<br \/>Una valvola progettata per aprire a 178 bar\u2026 aprir\u00e0 davvero a 178 bar? Oppure a 162? O magari a 196?<\/strong> <strong>Se sei un progettista industriale, conosci gi\u00e0 la risposta: dipende.<br \/>Dipende dalle tolleranze, dai processi, dall\u2019assemblaggio. E soprattutto da come queste variabili <em>interagiscono<\/em> tra loro. Questo articolo, tratto dal libro \u201cCasi pratici di approccio statistico alle tolleranze\u201d [1] \u00e8 un viaggio dentro quella zona grigia \u2014 dove la progettazione smette di essere deterministica e diventa probabilistica \u2014 e si riferisce a un caso semplice ma illuminante: una valvola di massima pressione.<\/strong><\/p>\n<p><em>di Luigi Pasquali<\/em><\/p>\n<h2 class=\"wp-block-heading\"><strong>La valvola: semplice\u2026 solo in apparenza<\/strong><\/h2>\n<p>Abbiamo una configurazione minimale:<\/p>\n<ol class=\"wp-block-list\">\n<li>Un bullone che funziona da otturatore mobile<\/li>\n<li>Un elemento di tenuta<\/li>\n<li>Una molla precaricata<\/li>\n<\/ol>\n<p>Supponendo che nella camera A la pressione del fluido aumenti in maniera quasi statica rispetto alla camera B, la molla mantiene la tenuta fino a quando la forza dovuta alla differenza di pressione non supera il precarico.<\/p>\n<p>Questa \u00e8 l\u2019equazione di equilibrio che consente di determinare a quale differenza di pressione la valvola interviene:<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.22.09.png?ssl=1\"><img loading=\"lazy\" fetchpriority=\"high\" decoding=\"async\" width=\"472\" height=\"164\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.22.09.png?resize=472%2C164&#038;ssl=1\" alt=\"\" class=\"wp-image-46081\" style=\"width:226px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.22.09.png?resize=472%2C164&#038;ssl=1 472w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.22.09-300x104.png 300w\" sizes=\"(max-width: 472px) 100vw, 472px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Dove:<\/p>\n<ul class=\"wp-block-list\">\n<li>k = rigidezza della molla<\/li>\n<\/ul>\n<p>Supponiamo la molla in esecuzione precisa, affetta da un errore del 10%:<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.07.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"82\" src=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.07.png?resize=444%2C82&#038;ssl=1\" alt=\"\" class=\"wp-image-46082\" style=\"width:249px;height:auto\" srcset=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.07.png?resize=444%2C82&#038;ssl=1 444w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.07-300x55.png 300w\" sizes=\"(max-width: 444px) 100vw, 444px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<ul class=\"wp-block-list\">\n<li>\u00a0= precarico<\/li>\n<\/ul>\n<p>L\u2019incertezza sul precarico deriva dalla ripetibilit\u00e0 del processo di assemblaggio del dispositivo ed \u00e8 stimata pari a:<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.45.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"364\" height=\"102\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.45.png?resize=364%2C102&#038;ssl=1\" alt=\"\" class=\"wp-image-46083\" style=\"width:205px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.45.png?resize=364%2C102&#038;ssl=1 364w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.23.45-300x84.png 300w\" sizes=\"(max-width: 364px) 100vw, 364px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<ul class=\"wp-block-list\">\n<li>d = diametro di passaggio<\/li>\n<\/ul>\n<p>Il foro di passaggio, realizzato in classe IT10, ha tolleranza:<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.24.27.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"86\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.24.27.png?resize=750%2C86&#038;ssl=1\" alt=\"\" class=\"wp-image-46084\" style=\"aspect-ratio:8.714893617021277;width:415px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.24.27.png?resize=750%2C86&#038;ssl=1 854w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.24.27-300x34.png 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.24.27-768x88.png 768w\" sizes=\"(max-width: 854px) 100vw, 854px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Con i valori nominali delle variabili, i 178 bar di differenza di pressione tornano perfettamente:<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.25.07.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"164\" src=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.25.07.png?resize=532%2C164&#038;ssl=1\" alt=\"\" class=\"wp-image-46085\" style=\"width:253px;height:auto\" srcset=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.25.07.png?resize=532%2C164&#038;ssl=1 532w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.25.07-300x92.png 300w\" sizes=\"(max-width: 532px) 100vw, 532px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p><strong>Il lato oscuro delle tolleranze: <\/strong>quanto influiscono le incertezze delle variabili di INPUT sul risultato finale?<\/p>\n<p><strong>L\u2019approccio tradizionale: WCA<\/strong><\/p>\n<p>La Worst Case Analysis opera in maniera semplice e brutale: considera tutti i parametri al limite di tolleranza\u2026 e nella direzione pi\u00f9 sconveniente.<\/p>\n<p>Ad esempio, la massima differenza di pressione si ottiene assumendo i termini del numeratore (costante elastica e precarico) ai loro valori massimi e, simultaneamente, il quadrato del diametro al denominatore al suo valore minimo.<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.34.23.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"548\" height=\"254\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.34.23.png?resize=548%2C254&#038;ssl=1\" alt=\"\" class=\"wp-image-46086\" style=\"width:290px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.34.23.png?resize=548%2C254&#038;ssl=1 548w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.34.23-300x139.png 300w\" sizes=\"(max-width: 548px) 100vw, 548px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Il risultato \u00e8 quello di assegnare alla pressione di intervento una incertezza ampia 80[bar], per quanto le configurazioni limite siano altamente improbabili a verificarsi.<\/p>\n<ul class=\"wp-block-list\">\n<li>pressione minima: <strong>141 bar<\/strong><\/li>\n<li>pressione massima: <strong>220 bar<\/strong><\/li>\n<\/ul>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.35.01.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"83\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.35.01-1024x113.png?resize=750%2C83&#038;ssl=1\" alt=\"\" class=\"wp-image-46087\" style=\"width:456px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.35.01-1024x113.png?resize=750%2C83&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.35.01-300x33.png 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.35.01-768x85.png 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.35.01.png 1032w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>La WCA non \u00e8 in grado di predire quale sar\u00e0 la percentuale di valvole che intervengono al di sotto o al di sopra di un valore di soglia prestabilito, ad esempio 160 [bar].<\/p>\n<h2 class=\"wp-block-heading\"><strong>Entriamo nel casin\u00f2 [2]: simulazione Monte Carlo<\/strong><\/h2>\n<p>La simulazione Monte Carlo cambia completamente il paradigma.<\/p>\n<p>Invece di indagare:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u201cqual \u00e8 il caso peggiore?\u201d<\/p>\n<p>Si domanda:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u201ccosa succede davvero, nella realt\u00e0 produttiva?\u201d<\/p>\n<p>Nello specifico, una analisi Monte Carlo:<\/p>\n<ul class=\"wp-block-list\">\n<li>genera migliaia di combinazioni realistiche di k, x<sub>0<\/sub>, d<\/li>\n<li>calcola per ogni combinazione, la pressione di intervento <em>p<sub>i<\/sub><\/em><\/li>\n<li>determina la distribuzione statistica della pressione di intervento <em>p<sub>i<\/sub><\/em><\/li>\n<\/ul>\n<p>In pratica, nel rispetto delle ipotesi di partenza, la simulazione <strong>assembla migliaia di valvole virtuali<\/strong> e ne prova di tutte la pressione di intervento <em>p<sub>i<\/sub><\/em>.<\/p>\n<h3 class=\"wp-block-heading\"><strong>Le ipotesi<\/strong><\/h3>\n<p>Assumendo che le tre variabili di input k, d, x<sub>0<\/sub>\u00a0siano distribuzioni gaussiane e che i relativi processi di realizzazione della molla, di foratura e di assemblaggio della valvola siano soggetti a controllo statistico e che abbiano CPK=CP = 1 [3], deriva:<\/p>\n<ul class=\"wp-block-list\">\n<li>k \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 valore medio= 70 [N\/mm] \u00a0\u00a0\u03c3<sub>k<\/sub>\u00a0 \u00a0= 14 \/ 6 \u2248 2,33 [N\/mm]<\/li>\n<li>d \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 valore medio = 5,006 [mm]\u00a0\u03c3<sub>d <\/sub>= 0,012 \/ 6 = 0,002 [mm]<\/li>\n<li>x<sub>0<\/sub>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 valore medio = 5 [mm]\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u03c3<sub>x0<\/sub>\u00a0\u00a0 \u00a0=1,2 \/ 6 = 0,2 [mm]<\/li>\n<\/ul>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-scaled.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"167\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-1024x228.jpg?resize=750%2C167&#038;ssl=1\" alt=\"\" class=\"wp-image-46088\" style=\"width:619px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-1024x228.jpg?resize=750%2C167&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-300x67.jpg 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-768x171.jpg 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-1536x342.jpg 1536w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-2-fotor-2026040812250-2048x456.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Se eseguiamo la simulazione in un foglio Excel\u00ae, potremo dedicare tre colonne alla generazione delle variabili di INPUT nel rispetto delle distribuzioni gaussiane appena descritte.<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-scaled.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"179\" src=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-1024x245.jpg?resize=750%2C179&#038;ssl=1\" alt=\"\" class=\"wp-image-46089\" style=\"width:632px;height:auto\" srcset=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-1024x245.jpg?resize=750%2C179&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-300x72.jpg 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-768x184.jpg 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-1536x368.jpg 1536w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-3-fotor-202604081257-2048x490.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Una quarta colonna calcola invece la pressione di intervento.<\/p>\n<p>Eseguite migliaia di simulazioni (a ognuna delle quali \u00e8 associata una riga del foglio di calcolo), si verifica che la pressione di intervento (output della simulazione) \u00e8 ben rappresentata da una distribuzione normale della quale possiamo stimare valore medio e deviazione:<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-4-fotor-2026040812743.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"126\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-4-fotor-2026040812743-1024x172.jpg?resize=750%2C126&#038;ssl=1\" alt=\"\" class=\"wp-image-46090\" style=\"width:626px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-4-fotor-2026040812743-1024x172.jpg?resize=750%2C126&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-4-fotor-2026040812743-300x50.jpg 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-4-fotor-2026040812743-768x129.jpg 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-4-fotor-2026040812743.jpg 1432w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>pressione media di intervento: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 178 bar<br \/>deviazione standard (\u03c3): \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0\u00b19 bar<\/p>\n<p>Trattandosi di una distribuzione normale, il 99,7% della popolazione di valvole avr\u00e0 una pressione di intervento compresa fra il valore medio \u00b13 volte la deviazione standard.<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.41.21.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"63\" src=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.41.21-1024x86.png?resize=750%2C63&#038;ssl=1\" alt=\"\" class=\"wp-image-46091\" style=\"width:589px;height:auto\" srcset=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.41.21-1024x86.png?resize=750%2C63&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.41.21-300x25.png 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.41.21-768x64.png 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.41.21.png 1478w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Il punto chiave \u00e8 che non solo l\u2019analisi Monte Carlo ha sensibilmente ridimensionato l\u2019intervallo di incertezza da attribuire alla pressione di intervento, quanto che rende possibile quantificare la probabilit\u00e0 che la pressione di intervento si trovi all\u2019interno di un intervallo prestabilito.<\/p>\n<p>Ad esempio, \u00e8 immediato calcolare che la probabilit\u00e0 di avere una valvola con pressione di intervento inferiore ai 160 bar \u00e8 di circa il 2,6%.<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"471\" src=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946-1024x643.jpg?resize=750%2C471&#038;ssl=1\" alt=\"\" class=\"wp-image-46092\" style=\"aspect-ratio:1.5926340674380988;width:597px;height:auto\" srcset=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946-1024x643.jpg?resize=750%2C471&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946-300x188.jpg 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946-768x482.jpg 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946-1536x964.jpg 1536w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-5-fotor-2026040812946-2048x1286.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>L\u2019aspetto entusiasmante della simulazione \u00e8 che rende possibile comparare l\u2019output statistico di scenari alternativi. Ad esempio, se assegniamo CPK=CP=1,33 ai dati di input (che equivale a ridurre le rispettive deviazioni standard del 25%), l\u2019aliquota di valvole con pressione di intervento al di sotto di 160 bar scende allo 0,5 %. Questo \u00e8 il confronto fra le distribuzioni della pressione di intervento a seconda del valore di CP=CPK considerato.<\/p>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"619\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247-1024x845.jpg?resize=750%2C619&#038;ssl=1\" alt=\"\" class=\"wp-image-46093\" style=\"width:518px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247-1024x845.jpg?resize=750%2C619&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247-300x248.jpg 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247-768x634.jpg 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247-1536x1267.jpg 1536w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-6-fotor-2026041015247.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/i1.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"70\" src=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25-1024x96.png?resize=750%2C70&#038;ssl=1\" alt=\"\" class=\"wp-image-46094\" style=\"width:591px;height:auto\" srcset=\"https:\/\/i0.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25-1024x96.png?resize=750%2C70&#038;ssl=1 1024w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25-300x28.png 300w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25-768x72.png 768w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25-1536x143.png 1536w, https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.51.25.png 1542w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-recalc-dims=\"1\"><\/a><\/figure>\n<h2 class=\"wp-block-heading\"><strong>Perch\u00e9 cambia il modo di progettare<\/strong><\/h2>\n<p>La simulazione Monte Carlo<\/p>\n<ul class=\"wp-block-list\">\n<li>assegna probabilit\u00e0 ai risultati<\/li>\n<\/ul>\n<ul class=\"wp-block-list\">\n<li>permette di valutare il rischio reale<\/li>\n<li>evita sovradimensionamenti costosi<\/li>\n<\/ul>\n<p>La WCA, al contrario, sovrastima tipicamente la variabilit\u00e0.<\/p>\n<h2 class=\"wp-block-heading\"><strong>Conclusione<\/strong><\/h2>\n<p>La differenza fra WCA o Monte Carlo \u00e8 prima di tutto culturale. La simulazione richiede:<\/p>\n<ul class=\"wp-block-list\">\n<li>di abbandonare un approccio deterministico a favore di uno probabilistico<\/li>\n<li>di passare dal voler \u201cgarantire tutto\u201d alla \u201cgestione del rischio\u201d<\/li>\n<\/ul>\n<p>La prossima volta che dimensioni un componente critico, chiediti: sto progettando per il caso peggiore\u2026 o per il mondo reale?<\/p>\n<p>Perch\u00e9 tra i due approcci, spesso, c\u2019\u00e8 in ballo il costo, la competitivit\u00e0 e il successo del prodotto.<\/p>\n<h3 class=\"wp-block-heading\"><strong>NOTE<\/strong><\/h3>\n<p><strong>[1]\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>\u201cCasi pratici di approccio statistico alle tolleranze\u201d<\/p>\n<p>\u00a0Luigi Pasquali, Amazon Publishing<\/p>\n<p><strong>[2]\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>L\u2019analisi Monte Carlo deve il suo nome al casin\u00f2 del principato di Monaco proprio perch\u00e9 si basa sulla generazione di numeri casuali per simulare la performance del sistema.<\/p>\n<p><strong>[3]\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>Assegnando distribuzione normale ai processi che definiscono k,<em><\/em> \u00a0, d<\/p>\n<ul class=\"wp-block-list\">\n<li>questi si dicono centrati se il valore medio cade a met\u00e0 del range di tolleranza assegnata (ovvero CPK=CP)<\/li>\n<li>e hanno CP=1 se il range di tolleranza \u00e8 pari a 6 volte la deviazione standard,<\/li>\n<\/ul>\n<p>dato che per definizione la capacit\u00e0 di processo vale:<\/p>\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.53.50.png?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"184\" src=\"https:\/\/i2.wp.com\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/Screenshot-2026-05-12-alle-12.53.50.png?resize=290%2C184&#038;ssl=1\" alt=\"\" class=\"wp-image-46096\" style=\"width:127px;height:auto\" data-recalc-dims=\"1\"><\/a><\/figure>\n<p>Avendo indicato\u00a0\u00a0 LS = limite superiore di tolleranza<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 LI = limite inferiore di tolleranza<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u03c3 = deviazione standard<\/p>\n<\/p>\n<\/div>\n<p>L&#8217;articolo <a href=\"https:\/\/www.ilprogettistaindustriale.it\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/\">Quando il valore nominale non basta: quantificare l\u2019incertezza con la simulazione Monte Carlo<\/a> sembra essere il primo su <a href=\"https:\/\/www.ilprogettistaindustriale.it\/\">Il Progettista Industriale<\/a>.<\/p>\n<\/div>\n<p><a href=\"https:\/\/www.ilprogettistaindustriale.it\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/\">Vai alla fonte.<\/a><\/p>\n<p>Autore: Emanuela Bianchi<\/p>\n<p class=\"wpematico_credit\"><small>Powered by <a href=\"http:\/\/www.wpematico.com\" target=\"_blank\" rel=\"noopener noreferrer\">WPeMatico<\/a><\/small><\/p>\n<p><strong>_________________________________<\/strong><\/p>\n<p><strong>CFD FEA Service SRL<\/strong> &egrave; una societ&agrave; di servizi che offre <em>consulenza<\/em> e <em>formazione<\/em> in ambito <strong>ingegneria<\/strong> e <strong>IT<\/strong>. Se questo post\/prodotto ti &egrave; piaciuto ti invitiamo a:<\/p>\n<ul>\n<li>visionare il nostro <a href=\"https:\/\/cfdfeaservice.it\/index.php\/blog\/\" target=\"_blank\" rel=\"noopener\">blog<\/a><\/li>\n<li>visionare i <a href=\"https:\/\/cfdfeaservice.it\/index.php\/prodotti\/\" target=\"_blank\" rel=\"noopener\">software<\/a> disponibili - anche per la formazione<\/li>\n<li>iscriverti alla nostra newsletter<\/li>\n<li>entrare in contatto con noi attraverso la <a href=\"https:\/\/cfdfeaservice.it\/#ribbon\" target=\"_blank\" rel=\"noopener\">pagina contatti<\/a><\/li>\n<\/ul>\n<p>Saremo lieti di seguire le tue richieste e fornire risposte alle tue domande.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nel mondo reale, le valvole non leggono i disegni.Una valvola progettata per aprire a 178 bar\u2026 aprir\u00e0 davvero a 178 bar? Oppure a 162? O magari a 196? Se sei un progettista industriale, conosci gi\u00e0 la risposta: dipende.Dipende dalle tolleranze, dai processi, dall\u2019assemblaggio. E soprattutto da come queste variabili interagiscono [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":24569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[57],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/test.cfdfeaservice.it\/wp-content\/uploads\/2026\/05\/IMG-1-fotor-2026040811545.jpg?fit=1744%2C1212&ssl=1","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quando il valore nominale non basta: quantificare l\u2019incertezza con la simulazione Monte Carlo - CFD FEA\/FEM Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando il valore nominale non basta: quantificare l\u2019incertezza con la simulazione Monte Carlo - CFD FEA\/FEM Service\" \/>\n<meta property=\"og:description\" content=\"Nel mondo reale, le valvole non leggono i disegni.Una valvola progettata per aprire a 178 bar\u2026 aprir\u00e0 davvero a 178 bar? Oppure a 162? O magari a 196? Se sei un progettista industriale, conosci gi\u00e0 la risposta: dipende.Dipende dalle tolleranze, dai processi, dall\u2019assemblaggio. E soprattutto da come queste variabili interagiscono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/\" \/>\n<meta property=\"og:site_name\" content=\"CFD FEA\/FEM Service\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cfdfeaservice\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T01:02:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.tecnichenuove.it\/ilprogettistaindustriale\/2026\/05\/IMG-1-fotor-2026040811545.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/#organization\",\"name\":\"CFD FEA SERVICE SRL\",\"url\":\"https:\/\/test.cfdfeaservice.it\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/cfdfeaservice\",\"https:\/\/www.linkedin.com\/company\/11421185\/\",\"https:\/\/www.youtube.com\/channel\/UCr2h1DbpsNDKJSBAgeWMbfA\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/#logo\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/i2.wp.com\/test.cfdfeaservice.it\/wp-content\/uploads\/2018\/07\/CFD-FEA-SERVICE-Compact.png?fit=677%2C178&ssl=1\",\"width\":677,\"height\":178,\"caption\":\"CFD FEA SERVICE SRL\"},\"image\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/#website\",\"url\":\"https:\/\/test.cfdfeaservice.it\/\",\"name\":\"CFD FEA\/FEM Service\",\"description\":\"Servizi di ingegneria 4.0\",\"publisher\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/test.cfdfeaservice.it\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#primaryimage\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/i2.wp.com\/test.cfdfeaservice.it\/wp-content\/uploads\/2026\/05\/IMG-1-fotor-2026040811545.jpg?fit=1744%2C1212&ssl=1\",\"width\":1744,\"height\":1212},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#webpage\",\"url\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/\",\"name\":\"Quando il valore nominale non basta: quantificare l\\u2019incertezza con la simulazione Monte Carlo - CFD FEA\/FEM Service\",\"isPartOf\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#primaryimage\"},\"datePublished\":\"2026-05-13T01:02:48+00:00\",\"dateModified\":\"2026-05-13T01:02:48+00:00\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/\"]}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\"},\"headline\":\"Quando il valore nominale non basta: quantificare l\\u2019incertezza con la simulazione Monte Carlo\",\"datePublished\":\"2026-05-13T01:02:48+00:00\",\"dateModified\":\"2026-05-13T01:02:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/test.cfdfeaservice.it\/index.php\/2026\/05\/13\/quando-il-valore-nominale-non-basta-quantificare-lincertezza-con-la-simulazione-monte-carlo\/#primaryimage\"},\"articleSection\":\"Normativa\",\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/#\/schema\/person\/c3b6ebdd7f80794fe6e6657f2f5335e7\",\"name\":\"CFD FEA SERVICE\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/test.cfdfeaservice.it\/#personlogo\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a34dbcf675cd4152f1184664b3adcb72?s=96&d=mm&r=g\",\"caption\":\"CFD FEA SERVICE\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","jetpack_shortlink":"https:\/\/wp.me\/p9JrPq-6og","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/24568"}],"collection":[{"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/comments?post=24568"}],"version-history":[{"count":0,"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/posts\/24568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media\/24569"}],"wp:attachment":[{"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/media?parent=24568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/categories?post=24568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.cfdfeaservice.it\/index.php\/wp-json\/wp\/v2\/tags?post=24568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}